{"id":108,"date":"2010-10-01T20:30:13","date_gmt":"2010-10-01T19:30:13","guid":{"rendered":"http:\/\/blog.epbcn.com\/?p=108"},"modified":"2017-02-22T13:18:49","modified_gmt":"2017-02-22T12:18:49","slug":"ciclo-de-encuentros-pensar-lo-inconsciente-que-es-el-psicoanalisis","status":"publish","type":"post","link":"https:\/\/www.epbcn.com\/blog\/2010\/10\/01\/ciclo-de-encuentros-pensar-lo-inconsciente-que-es-el-psicoanalisis\/","title":{"rendered":"Ciclo de encuentros \u201cPensar lo inconsciente\u201d: \u00bfQu\u00e9 es el psicoan\u00e1lisis?"},"content":{"rendered":"<p style=\"text-align: center;\">Ciclo de encuentros<br \/>\n<a href=\"\/difusion\/ciclos-de-encuentros\/pensar-lo-inconsciente-2010\/\"><span style=\"text-decoration: underline;\">Pensar lo inconsciente<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><strong>\u00bfQu\u00e9 es el psicoan\u00e1lisis?<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>A cargo de:<\/strong><br \/>\n<a title=\"Mar\u00eda del Mar Mart\u00edn\" href=\"\/equipo\/maria-del-mar-martin\/\" target=\"_blank\">Mar\u00eda del Mar Mart\u00edn<\/a>\u00a0y\u00a0<a title=\"Silvina Fern\u00e1ndez\" href=\"\/equipo\/silvina-fernandez\/\" target=\"_blank\">Silvina Fern\u00e1ndez<\/a>, psicoanalistas.<\/p>\n<p style=\"text-align: center;\"><strong>D\u00eda y hora:<\/strong><br \/>\nViernes, 1 de octubre de 2010, a las 20:30.<\/p>\n<p style=\"text-align: center;\"><strong>Lugar:<\/strong><br \/>\nAulario del EPBCN. Balmes, 32, 2\u00ba 1\u00aa &#8211; 08007 Barcelona.<\/p>\n<p style=\"text-align: center;\"><strong>ASISTENCIA GRATUITA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Informaci\u00f3n e inscripciones:<\/strong><br \/>\n93 454 89 78,\u00a0secretaria@epbcn.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciclo de encuentros Pensar lo inconsciente \u00bfQu\u00e9 es el psicoan\u00e1lisis? A cargo de: Mar\u00eda del Mar Mart\u00edn\u00a0y\u00a0Silvina Fern\u00e1ndez, psicoanalistas. D\u00eda y hora: Viernes, 1 de octubre de 2010, a las 20:30. Lugar: Aulario del EPBCN. Balmes, 32, 2\u00ba 1\u00aa &#8211; 08007 Barcelona. ASISTENCIA GRATUITA Informaci\u00f3n e inscripciones: 93 454 89 78,\u00a0secretaria@epbcn.com<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[142,154],"class_list":["post-108","post","type-post","status-publish","format-standard","hentry","category-encuentros","tag-maria-del-mar-martin","tag-silvina-fernandez"],"_links":{"self":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/comments?post=108"}],"version-history":[{"count":0,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/108\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/media?parent=108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/categories?post=108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/tags?post=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}