{"id":1534,"date":"2010-10-24T20:30:43","date_gmt":"2010-10-24T19:30:43","guid":{"rendered":"http:\/\/blog.epbcn.com\/?p=1534"},"modified":"2017-02-22T13:18:07","modified_gmt":"2017-02-22T12:18:07","slug":"charla-coloquio-que-es-el-psicoanalisis-9","status":"publish","type":"post","link":"https:\/\/www.epbcn.com\/blog\/2010\/10\/24\/charla-coloquio-que-es-el-psicoanalisis-9\/","title":{"rendered":"Charla-coloquio: \u00bfQu\u00e9 es el psicoan\u00e1lisis?"},"content":{"rendered":"<div>\n<p style=\"text-align: center;\"><em>Charla-coloquio<\/em><\/p>\n<p style=\"text-align: center;\"><strong>\u00bfQu\u00e9 es el psicoan\u00e1lisis?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>A cargo de: <\/strong><br \/>\nAnabel L\u00f3pez y <a title=\"Mar\u00eda del Mar Mart\u00edn\" href=\"\/equipo\/maria-del-mar-martin\/\" target=\"_blank\">Mar\u00eda del Mar Mart\u00edn<\/a>, psicoanalistas.<\/p>\n<p style=\"text-align: center;\"><strong>D\u00eda y hora:<\/strong><br \/>\nViernes, 24 de octubre de 2006, a las 20:30.<\/p>\n<p style=\"text-align: center;\"><strong>Lugar:<\/strong><br \/>\nAulario del EPBCN. Balmes, 32, 2\u00ba 1\u00aa \u2013 08007 Barcelona.<\/p>\n<p style=\"text-align: center;\"><strong>ASISTENCIA GRATUITA<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Charla-coloquio \u00bfQu\u00e9 es el psicoan\u00e1lisis? A cargo de: Anabel L\u00f3pez y Mar\u00eda del Mar Mart\u00edn, psicoanalistas. D\u00eda y hora: Viernes, 24 de octubre de 2006, a las 20:30. Lugar: Aulario del EPBCN. Balmes, 32, 2\u00ba 1\u00aa \u2013 08007 Barcelona. ASISTENCIA GRATUITA<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[142],"class_list":["post-1534","post","type-post","status-publish","format-standard","hentry","category-charlas-coloquio","tag-maria-del-mar-martin"],"_links":{"self":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/comments?post=1534"}],"version-history":[{"count":0,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1534\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/media?parent=1534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/categories?post=1534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/tags?post=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}