{"id":1804,"date":"2011-09-01T10:00:25","date_gmt":"2011-09-01T09:00:25","guid":{"rendered":"http:\/\/blog.epbcn.com\/?p=1804"},"modified":"2017-02-22T13:09:29","modified_gmt":"2017-02-22T12:09:29","slug":"m%c2%aa-del-mar-martin-en-el-reportaje-decide-tu-sexualidad-de-psycologies","status":"publish","type":"post","link":"https:\/\/www.epbcn.com\/blog\/2011\/09\/01\/m%c2%aa-del-mar-martin-en-el-reportaje-decide-tu-sexualidad-de-psycologies\/","title":{"rendered":"Mar\u00eda del Mar Mart\u00edn en el reportaje \u201cDecide c\u00f3mo vivir tu sexualidad\u201d de Psychologies"},"content":{"rendered":"<p>La psicoanalista <a title=\"Mar\u00eda del Mar Mart\u00edn\" href=\"\/equipo\/maria-del-mar-martin\/\" target=\"_blank\">Mar\u00eda del Mar Mart\u00edn<\/a>\u00a0fue entrevistada para el reportaje &#8220;<a href=\"\/pdf\/prensa\/revistas\/psychologies\/2011-09-Decide-como-vivir-tu-sexualidad.pdf\" target=\"_blank\">Decide c\u00f3mo vivir tu sexualidad<\/a>&#8221; por el periodista Jos\u00e9 Andr\u00e9s Rodr\u00edguez. Reportaje publicado en la revista Psychologies en septiembre de 2011.<\/p>\n<p><a href=\"\/pdf\/prensa\/revistas\/psychologies\/2011-09-Decide-como-vivir-tu-sexualidad.pdf\" target=\"_blank\">Reportaje en formato\u00a0pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La psicoanalista Mar\u00eda del Mar Mart\u00edn\u00a0fue entrevistada para el reportaje &#8220;Decide c\u00f3mo vivir tu sexualidad&#8221; por el periodista Jos\u00e9 Andr\u00e9s Rodr\u00edguez. Reportaje publicado en la revista Psychologies en septiembre de 2011. Reportaje en formato\u00a0pdf<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[142],"class_list":["post-1804","post","type-post","status-publish","format-standard","hentry","category-psychologies","tag-maria-del-mar-martin"],"_links":{"self":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/comments?post=1804"}],"version-history":[{"count":0,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1804\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/media?parent=1804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/categories?post=1804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/tags?post=1804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}