{"id":1855,"date":"2011-11-04T11:47:17","date_gmt":"2011-11-04T10:47:17","guid":{"rendered":"http:\/\/blog.epbcn.com\/?p=1855"},"modified":"2019-10-12T15:29:59","modified_gmt":"2019-10-12T14:29:59","slug":"clase-inaugural-a-la-xv-convocatoria-del-curso-de-introduccion-al-psicoanalisis-los-suenos","status":"publish","type":"post","link":"https:\/\/www.epbcn.com\/blog\/2011\/11\/04\/clase-inaugural-a-la-xv-convocatoria-del-curso-de-introduccion-al-psicoanalisis-los-suenos\/","title":{"rendered":"Clase inaugural a la XV convocatoria del Curso de introducci\u00f3n al psicoan\u00e1lisis: Los sue\u00f1os"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\">CURSO DE INTRODUCCI\u00d3N AL PSICOAN\u00c1LISIS<\/span><br \/>\nXV CONVOCATORIA, CURSO 2011-2012<\/p>\n<p style=\"text-align: center;\"><em>Clase Inaugural<\/em><br \/>\n<strong>LOS SUE\u00d1OS<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>A cargo de:<\/strong><\/p>\n<p style=\"text-align: center;\"><a title=\"Josep Maria Blasco\" href=\"\/equipo\/josep-maria-blasco\/\" target=\"_blank\" rel=\"noopener noreferrer\">Josep Maria Blasco<\/a>, codirector del Espacio Psicoanal\u00edtico de Barcelona y profesor del curso.<\/p>\n<p style=\"text-align: center;\"><strong>D\u00eda y hora:<\/strong><br \/>\nMi\u00e9rcoles, 9 de noviembre de 2011, de 11:00 \u00a0a 12:15 h y de 21:00 \u00a0a 22:15.<\/p>\n<p style=\"text-align: center;\"><strong>Lugar:<\/strong><br \/>\nAulario del EPBCN. Balmes, 32, 2\u00ba 1\u00aa &#8211; 08007 Barcelona.<\/p>\n<p style=\"text-align: center;\"><strong>ASISTENCIA GRATUITA &#8211; PLAZAS LIMITADAS<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Informaci\u00f3n e inscripciones:<\/strong><br \/>\n93 454 89 78, secretaria@epbcn.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CURSO DE INTRODUCCI\u00d3N AL PSICOAN\u00c1LISIS XV CONVOCATORIA, CURSO 2011-2012 Clase Inaugural LOS SUE\u00d1OS A cargo de: Josep Maria Blasco, codirector del Espacio Psicoanal\u00edtico de Barcelona y profesor del curso. D\u00eda y hora: Mi\u00e9rcoles, 9 de noviembre de 2011, de 11:00 \u00a0a 12:15 h y de 21:00 \u00a0a 22:15. Lugar: Aulario del EPBCN. Balmes, 32, 2\u00ba [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,16],"tags":[133],"class_list":["post-1855","post","type-post","status-publish","format-standard","hentry","category-curso-de-introduccion","category-reuniones-inaugurales","tag-josep-maria-blasco"],"_links":{"self":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/comments?post=1855"}],"version-history":[{"count":0,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/posts\/1855\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/media?parent=1855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/categories?post=1855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epbcn.com\/blog\/wp-json\/wp\/v2\/tags?post=1855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}